{"id":238263,"date":"2016-08-12T13:31:11","date_gmt":"2016-08-12T11:31:11","guid":{"rendered":"http:\/\/sunds.pandavisuals.de\/?p=238263"},"modified":"2025-03-14T12:27:14","modified_gmt":"2025-03-14T11:27:14","slug":"scansource-auf-der-jtl-connect","status":"publish","type":"post","link":"https:\/\/sundsits.com\/en\/scansource-auf-der-jtl-connect\/","title":{"rendered":"Scansource auf der JTL Connect"},"content":{"rendered":"<p><img decoding=\"async\" class=\"size-full wp-image-238256 alignnone\" src=\"https:\/\/sundsits.com\/wp-content\/uploads\/2019\/05\/scansource-logo.png\" alt=\"\" width=\"227\" height=\"49\" title=\"\" srcset=\"https:\/\/sundsits.com\/wp-content\/uploads\/2019\/05\/scansource-logo.png 227w, https:\/\/sundsits.com\/wp-content\/uploads\/2019\/05\/scansource-logo-150x32.png 150w\" sizes=\"(max-width: 227px) 100vw, 227px\" \/><\/p>\n<p><strong>Scansource<\/strong><\/p>\n<p>Scansource ist ein globaler Anbieter f\u00fcr Technologie Produkte und L\u00f6sungen.<\/p>\n<p>Das Produktportfolio mit dem\u00a0 Scansource arbeitet ist f\u00fcr &#8220;Point-of-sale&#8221;, Barcode, sowie physische Sicherheit und Video-Sprach-und Datennetzwerke entwickelt worden.<br \/>\nAuf Grund der Zusammenarbeit mit Scansource k\u00f6nnen wir unseren Kunden eine hohe Verf\u00fcgbarkeit und eine schnelle Lieferung an Hardware f\u00fcr das WMS, die Wawi, sowie f\u00fcr den LS-Pos bieten.<br \/>\nDurch ein gro\u00dfes europ\u00e4isches Lager haben wir die Hardware immer bereitstehen und k\u00f6nnen Ihnen schnell\u00a0 s\u00e4mtliche Produkte zukommen lassen.<br \/>\nDurch die Partnerschaft k\u00f6nnen wir Ihnen in k\u00fcrzester Zeit gro\u00dfe Mengen an Hardware installiert mit unserer Software \u00fcbermitteln.<br \/>\nWenn Sie bestimmte W\u00fcnsche haben, wie die Farb\u00e4nderung des Hardware Geh\u00e4uses, dann sprechen Sie uns an.<br \/>\nF\u00fcr weitere Informationen k\u00f6nnen Sie uns gerne auf der JTL Connect besuchen kommen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Scansource Scansource ist ein globaler Anbieter f\u00fcr Technologie Produkte und L\u00f6sungen. Das Produktportfolio mit dem\u00a0 Scansource arbeitet ist f\u00fcr &#8220;Point-of-sale&#8221;, Barcode, sowie physische Sicherheit und Video-Sprach-und Datennetzwerke entwickelt worden. Auf Grund der Zusammenarbeit mit Scansource k\u00f6nnen wir unseren Kunden eine hohe Verf\u00fcgbarkeit und eine schnelle Lieferung an Hardware f\u00fcr das WMS, die Wawi, sowie f\u00fcr [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_angie_page":false,"page_builder":"","footnotes":""},"categories":[33],"tags":[],"class_list":["post-238263","post","type-post","status-publish","format-standard","hentry","category-nicht-kategorisiert"],"_links":{"self":[{"href":"https:\/\/sundsits.com\/en\/wp-json\/wp\/v2\/posts\/238263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sundsits.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sundsits.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sundsits.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sundsits.com\/en\/wp-json\/wp\/v2\/comments?post=238263"}],"version-history":[{"count":0,"href":"https:\/\/sundsits.com\/en\/wp-json\/wp\/v2\/posts\/238263\/revisions"}],"wp:attachment":[{"href":"https:\/\/sundsits.com\/en\/wp-json\/wp\/v2\/media?parent=238263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sundsits.com\/en\/wp-json\/wp\/v2\/categories?post=238263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sundsits.com\/en\/wp-json\/wp\/v2\/tags?post=238263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}